{"id":1879,"date":"2018-08-14T11:51:48","date_gmt":"2018-08-14T09:51:48","guid":{"rendered":"http:\/\/hotelvalbrenta.com.netechlab.it\/uncategorized\/jazz-movie\/"},"modified":"2018-08-14T11:51:48","modified_gmt":"2018-08-14T09:51:48","slug":"jazz-movie","status":"publish","type":"post","link":"https:\/\/www.hotelvalbrenta.com\/en\/menu-speciali-en\/jazz-movie\/","title":{"rendered":"JAZZ &#038; MOVIE"},"content":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1532418743945{background-color: #efede8 !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_column_text]<\/p>\n<h4><b>JAZZ &amp;MOVIE<\/b><br \/>\nSe siete appassionati di CINEMA e di JAZZ, vi aspettiamo venerd\u00ec 30 giugno 2017 presso il Ristorante &#8220;Il Tulipano&#8221; di Limena per la cena-concerto &#8220;JAZZ &amp; MOVIE&#8221;.<\/h4>\n<p>Faremo insieme un viaggio musicale, in chiave intimistica, nei rapporti tra la musica Jazz ed il cinema, dagli anni 30 fino ai giorni nostri. Il repertorio \u00e8 un&#8217;antologia di brani selezionati tra le canzoni pi\u00f9 amate dal pubblico, introdotte da una breve presentazione per rivivere le scene pi\u00f9 belle dei film che le hanno rese celebri. Le portate ed i vini serviti durante tutta la cena sono frutto di una accurata selezione per realizzare l&#8217;abbinamento perfetto con l&#8217;atmosfera della serata e le canzoni del concerto.[\/vc_column_text]<div class=\" porto-btn-ctn-left \"><a class=\"porto-btn porto-adjust-bottom-margin porto-btn-normal porto-btn-no-hover-bg  porto-btn-left \"  rel='' href = \"http:\/\/www.hotelvalbrenta.com\/contatti\/\"  data-hover=\"\" data-border-color=\"\" data-bg=\"#005050\" data-hover-bg=\"\" data-border-hover=\"\" data-shadow-click=\"none\" data-shadow=\"\" style=\"border:none;background: #005050;color: #ffffff;\"><span class=\"porto-btn-hover\"><\/span><span class=\"porto-btn-data porto-btn-text \" >PRENOTA SUBITO!<\/span><\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_single_image image=&#8221;1633&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1532418743945{background-color: #efede8 !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_empty_space][vc_column_text] JAZZ &amp;MOVIE Se siete appassionati di CINEMA e di JAZZ, vi aspettiamo venerd\u00ec 30 giugno 2017 presso il Ristorante &#8220;Il Tulipano&#8221; di Limena per la cena-concerto &#8220;JAZZ &amp; MOVIE&#8221;. Faremo insieme un viaggio musicale, in chiave intimistica, nei rapporti tra la musica Jazz ed il cinema, dagli anni 30 fino [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[25],"tags":[],"_links":{"self":[{"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/posts\/1879"}],"collection":[{"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/comments?post=1879"}],"version-history":[{"count":1,"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/posts\/1879\/revisions"}],"predecessor-version":[{"id":1880,"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/posts\/1879\/revisions\/1880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/media\/1634"}],"wp:attachment":[{"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/media?parent=1879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/categories?post=1879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hotelvalbrenta.com\/en\/wp-json\/wp\/v2\/tags?post=1879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}